{"id":12365,"date":"2019-05-29T15:16:00","date_gmt":"2019-05-29T15:16:00","guid":{"rendered":"https:\/\/devalt-kambatiag.savviihq.com\/?p=12365"},"modified":"2023-09-12T15:16:18","modified_gmt":"2023-09-12T13:16:18","slug":"un-ubo-ne-s-arrete-pas-a-la-frontiere-nationale","status":"publish","type":"post","link":"https:\/\/www.altares.be\/fr\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/","title":{"rendered":"Un UBO ne s\u2019arr\u00eate pas \u00e0 la fronti\u00e8re nationale"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le d\u00e9fi majeur de votre processus KYC (Know Your Customer) r\u00e9side sans doute dans l\u2019identification des b\u00e9n\u00e9ficiaires effectifs \u2013 les UBO (Ultimate Beneficial Owners). Tout particuli\u00e8rement \u00e0 une \u00e9poque o\u00f9 les entreprises d\u00e9finissent la structure de leur organisation de mani\u00e8re \u00e0 en tirer le plus grand b\u00e9n\u00e9fice possible sur le plan financier, dans le but de cr\u00e9er un climat fiscal favorable, par exemple. Cette pratique donne souvent lieu \u00e0 des situations complexes qui ne s\u2019arr\u00eatent g\u00e9n\u00e9ralement pas aux fronti\u00e8res nationales. Mais comment obtenir un aper\u00e7u clair de la structure d\u2019une organisation sans ralentir votre processus KYC ?<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens.jpg\" alt=\"Photo a\u00e9rienne prise pendant la nuit\" class=\"wp-image-36241\" srcset=\"https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens.jpg 900w, https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens-300x169.jpg 300w, https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens-150x84.jpg 150w, https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens-768x432.jpg 768w, https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens-18x10.jpg 18w, https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens-24x13.jpg 24w, https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens-36x20.jpg 36w, https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/Een-UBO-stopt-niet-bij-de-landsgrens-48x27.jpg 48w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Les UBO : connaissez v\u00e9ritablement les personnes avec lesquelles vous entamez une collaboration<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tout commence par l\u2019identification des UBO. En g\u00e9n\u00e9ral, il s\u2019agit des personnes physiques qui d\u00e9tiennent directement ou indirectement, par l\u2019interm\u00e9diaire de parts ou de droits de vote, une participation de plus de 25 % dans une entit\u00e9 ou encore qui exercent un contr\u00f4le direct sur celle-ci d\u2019une mani\u00e8re ou d\u2019une autre. S\u2019il n\u2019en existe pas, le personnel dirigeant ou les cadres sup\u00e9rieurs sont d\u00e9sign\u00e9s comme \u00e9tant les UBO. Ces personnes sont alors appel\u00e9es des \u00ab pseudo-UBO \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9tant donn\u00e9 qu\u2019une organisation est souvent compos\u00e9e de diverses strates, d\u2019une soci\u00e9t\u00e9 m\u00e8re et de diff\u00e9rentes filiales, l\u2019identification des b\u00e9n\u00e9ficiaires effectifs se r\u00e9v\u00e8le assez compliqu\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quels risques encourez-vous si vous ignorez l\u2019identit\u00e9 des b\u00e9n\u00e9ficiaires effectifs ? Vous pourriez ni plus ni moins collaborer avec une entreprise indirectement li\u00e9e, par exemple, \u00e0 un trafic ill\u00e9gal d\u2019armes, au financement du terrorisme, \u00e0 l\u2019esclavage d\u2019enfants ou \u00e0 du blanchiment de capitaux. Autant de d\u00e9rives que vous voulez \u00e0 tout prix \u00e9viter.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un UBO est-il identifiable avec certitude ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il est tr\u00e8s probable que les b\u00e9n\u00e9ficiaires effectifs d\u2019une entit\u00e9 ne soient pas \u00e9tablis dans le pays dans lequel se situe l\u2019organisation. Ainsi, pr\u00e8s de 70 % des soci\u00e9t\u00e9s anonymes n\u00e9erlandaises sont directement li\u00e9es par des actions \u00e0 une autre entreprise \u00e9tablie aux Pays-Bas ou dans un autre pays. Plusieurs pays ont d\u00e9j\u00e0 mis en place un \u00ab registre UBO \u00bb qui reprend tous les b\u00e9n\u00e9ficiaires effectifs. \u00c0 l\u2019heure actuelle, ces pays ne sont pas soumis \u00e0 l\u2019obligation l\u00e9gale de v\u00e9rifier les informations contenues dans ce registre. En d\u2019autres termes, \u00e0 l\u2019heure actuelle, il n\u2019est pas simple d\u2019identifier avec certitude les b\u00e9n\u00e9ficiaires effectifs et donc de savoir avec qui vous collaborez r\u00e9ellement.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les donn\u00e9es peuvent faire la lumi\u00e8re sur le myst\u00e8re<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le manque de transparence constitue un d\u00e9fi majeur pour la plupart des organisations. En outre, il ne suffit pas \u00e0 une entreprise de respecter les exigences l\u00e9gales minimales pour se mettre hors de danger. Les entreprises actives \u00e0 l\u2019international doivent prendre toutes les mesures n\u00e9cessaires en vue de limiter les risques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une source externe peut apporter cette aide n\u00e9cessaire. Le nuage de donn\u00e9es de Dun &amp; Bradstreet en est un exemple. Cette base de donn\u00e9es en ligne est la source de donn\u00e9es la plus compl\u00e8te et fiable pour obtenir un aper\u00e7u des relations nationales et internationales de vos partenaires commerciaux, des petites entreprises peu connues aux puissantes multinationales qui disposent de milliers de filiales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les r\u00e9ponses \u00e0 vos questions<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce aux donn\u00e9es externes, vous obtenez une r\u00e9ponse aux questions suivantes :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quel est le v\u00e9ritable nom (officiel) et quelle est la v\u00e9ritable adresse de votre client\u00a0?&nbsp;<\/li>\n\n\n\n<li>Quelles sont pr\u00e9cis\u00e9ment les activit\u00e9s de votre client (potentiel) ? Il est possible que les activit\u00e9s effectives ne correspondent pas aux activit\u00e9s que le potentiel client a indiqu\u00e9es. Dans un tel cas de figure, vous devrez vous pencher sur ce point avant d\u2019entamer une collaboration avec cette partie.&nbsp;<\/li>\n\n\n\n<li>Votre client appartient-il \u00e0 un groupe plus vaste ? Poss\u00e8de-t-il, par exemple, une soci\u00e9t\u00e9 m\u00e8re ? Ou une filiale ? Si tel est le cas, quelles sont les autres entreprises de cette structure ? Le groupe d\u2019entreprises peut s\u2019\u00e9tendre au-del\u00e0 des fronti\u00e8res nationales. M\u00eame si votre client est actif \u00e0 l\u2019\u00e9chelon local, vous devrez avoir acc\u00e8s \u00e0 ses donn\u00e9es globales.&nbsp;<\/li>\n\n\n\n<li>Qui sont les ayants droit \u00e9conomiques de votre client ? Et peut-\u00eatre plus important encore : qui sont les ayants droit \u00e9conomiques de l\u2019organisation globale de votre client ?&nbsp;<\/li>\n\n\n\n<li>Quelle est l\u2019identit\u00e9 des principaux dirigeants ? Qui sont les principaux dirigeants au sein de la soci\u00e9t\u00e9 m\u00e8re ? Ces dirigeants assument-ils \u00e9galement des responsabilit\u00e9s dans d\u2019autres entreprises ? Si oui, ces entreprises sont-elles l\u00e9gitimes ?&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En ayant acc\u00e8s \u00e0 toutes ces informations \u00e0 partir d\u2019une seule source de donn\u00e9es, vous acc\u00e9l\u00e9rez le processus KYC et avez la certitude de b\u00e9n\u00e9ficier d\u2019un aper\u00e7u exhaustif et global de vos clients et fournisseurs.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9fi majeur de votre processus KYC (Know Your Customer) r\u00e9side sans doute dans l\u2019identification des b\u00e9n\u00e9ficiaires effectifs \u2013 les UBO (Ultimate Beneficial Owners). Comment obtenir un aper\u00e7u clair de la structure d\u2019une organisation sans ralentir votre processus KYC ?<\/p>","protected":false},"author":5,"featured_media":12366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-12365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compliance"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Een UBO stopt niet bij de landsgrens - Altares<\/title>\n<meta name=\"description\" content=\"Jouw risico als je niet weet wie de UBO\u2019s zijn? Je zou zomaar zaken kunnen doen met een bedrijf dat indirect gelinkt is aan bijvoorbeeld witwasserij, financiering van terrorisme of slavernij.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altares.be\/fr\/blog\/compliance\/un-ubo-ne-s-arrete-pas-a-la-frontiere-nationale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Een UBO stopt niet bij de landsgrens\" \/>\n<meta property=\"og:description\" content=\"Jouw risico als je niet weet wie de UBO\u2019s zijn? Je zou zomaar zaken kunnen doen met een bedrijf dat indirect gelinkt is aan bijvoorbeeld witwasserij, financiering van terrorisme of slavernij.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altares.be\/fr\/blog\/compliance\/un-ubo-ne-s-arrete-pas-a-la-frontiere-nationale\/\" \/>\n<meta property=\"og:site_name\" content=\"Altares\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-29T15:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T13:16:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/BE_Compliance_IntUBO-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anne de Geus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Een UBO stopt niet bij de landsgrens\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.altares.be\/wp-content\/uploads\/2021\/03\/Een-UBO-stopt-niet-bij-de-landsgrens.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anne de Geus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/\"},\"author\":{\"name\":\"Anne de Geus\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/#\\\/schema\\\/person\\\/51de691f2083dfb43a1308c2f4b31b25\"},\"headline\":\"Een UBO stopt niet bij de landsgrens\",\"datePublished\":\"2019-05-29T15:16:00+00:00\",\"dateModified\":\"2023-09-12T13:16:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/\"},\"wordCount\":681,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altares.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/nasa-_SFJhRPzJHs-unsplash-scaled.jpg\",\"articleSection\":[\"Compliance\"],\"inLanguage\":\"fr-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/\",\"url\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/\",\"name\":\"Een UBO stopt niet bij de landsgrens - Altares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altares.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/nasa-_SFJhRPzJHs-unsplash-scaled.jpg\",\"datePublished\":\"2019-05-29T15:16:00+00:00\",\"dateModified\":\"2023-09-12T13:16:18+00:00\",\"description\":\"Jouw risico als je niet weet wie de UBO\u2019s zijn? Je zou zomaar zaken kunnen doen met een bedrijf dat indirect gelinkt is aan bijvoorbeeld witwasserij, financiering van terrorisme of slavernij.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altares.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/nasa-_SFJhRPzJHs-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altares.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/nasa-_SFJhRPzJHs-unsplash-scaled.jpg\",\"width\":2560,\"height\":1704,\"caption\":\"Een UBO stopt niet bij de landsgrens\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/blog\\\/compliance\\\/een-ubo-stopt-niet-bij-de-landsgrens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.altares.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Een UBO stopt niet bij de landsgrens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/#website\",\"url\":\"https:\\\/\\\/www.altares.be\\\/\",\"name\":\"Altares\",\"description\":\"part of the Dun &amp; Bradstreet worldwide network\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altares.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/#organization\",\"name\":\"Altares\",\"url\":\"https:\\\/\\\/www.altares.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.altares.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Altares_RGB_liggend.svg\",\"contentUrl\":\"https:\\\/\\\/www.altares.be\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/Altares_RGB_liggend.svg\",\"width\":145.57333,\"height\":20.52,\"caption\":\"Altares\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altares.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altares.be\\\/#\\\/schema\\\/person\\\/51de691f2083dfb43a1308c2f4b31b25\",\"name\":\"Anne de Geus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f637b195224280571c9d07af4b1944ab0828c5f570216b88cc1631795077e5eb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f637b195224280571c9d07af4b1944ab0828c5f570216b88cc1631795077e5eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f637b195224280571c9d07af4b1944ab0828c5f570216b88cc1631795077e5eb?s=96&d=mm&r=g\",\"caption\":\"Anne de Geus\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un UBO ne s\u2019arr\u00eate pas \u00e0 la fronti\u00e8re nationale \u2013 Altares","description":"Quels risques encourez-vous si vous ignorez l\u2019identit\u00e9 des b\u00e9n\u00e9ficiaires effectifs ? Vous pourriez ni plus ni moins collaborer avec une entreprise indirectement li\u00e9e, par exemple, au blanchiment d\u2019argent, au financement du terrorisme ou \u00e0 l\u2019esclavage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altares.be\/fr\/blog\/compliance\/un-ubo-ne-s-arrete-pas-a-la-frontiere-nationale\/","og_locale":"fr_FR","og_type":"article","og_title":"Een UBO stopt niet bij de landsgrens","og_description":"Jouw risico als je niet weet wie de UBO\u2019s zijn? Je zou zomaar zaken kunnen doen met een bedrijf dat indirect gelinkt is aan bijvoorbeeld witwasserij, financiering van terrorisme of slavernij.","og_url":"https:\/\/www.altares.be\/fr\/blog\/compliance\/un-ubo-ne-s-arrete-pas-a-la-frontiere-nationale\/","og_site_name":"Altares","article_published_time":"2019-05-29T15:16:00+00:00","article_modified_time":"2023-09-12T13:16:18+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.altares.be\/wp-content\/uploads\/2019\/05\/BE_Compliance_IntUBO-1.png","type":"image\/png"}],"author":"Anne de Geus","twitter_card":"summary_large_image","twitter_title":"Een UBO stopt niet bij de landsgrens","twitter_image":"https:\/\/www.altares.be\/wp-content\/uploads\/2021\/03\/Een-UBO-stopt-niet-bij-de-landsgrens.png","twitter_misc":{"\u00c9crit par":"Anne de Geus","Dur\u00e9e de lecture est.":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/#article","isPartOf":{"@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/"},"author":{"name":"Anne de Geus","@id":"https:\/\/www.altares.be\/#\/schema\/person\/51de691f2083dfb43a1308c2f4b31b25"},"headline":"Een UBO stopt niet bij de landsgrens","datePublished":"2019-05-29T15:16:00+00:00","dateModified":"2023-09-12T13:16:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/"},"wordCount":681,"commentCount":0,"publisher":{"@id":"https:\/\/www.altares.be\/#organization"},"image":{"@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altares.be\/wp-content\/uploads\/2021\/03\/nasa-_SFJhRPzJHs-unsplash-scaled.jpg","articleSection":["Compliance"],"inLanguage":"fr-BE"},{"@type":"WebPage","@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/","url":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/","name":"Un UBO ne s\u2019arr\u00eate pas \u00e0 la fronti\u00e8re nationale \u2013 Altares","isPartOf":{"@id":"https:\/\/www.altares.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/#primaryimage"},"image":{"@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altares.be\/wp-content\/uploads\/2021\/03\/nasa-_SFJhRPzJHs-unsplash-scaled.jpg","datePublished":"2019-05-29T15:16:00+00:00","dateModified":"2023-09-12T13:16:18+00:00","description":"Quels risques encourez-vous si vous ignorez l\u2019identit\u00e9 des b\u00e9n\u00e9ficiaires effectifs ? Vous pourriez ni plus ni moins collaborer avec une entreprise indirectement li\u00e9e, par exemple, au blanchiment d\u2019argent, au financement du terrorisme ou \u00e0 l\u2019esclavage.","breadcrumb":{"@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/#primaryimage","url":"https:\/\/www.altares.be\/wp-content\/uploads\/2021\/03\/nasa-_SFJhRPzJHs-unsplash-scaled.jpg","contentUrl":"https:\/\/www.altares.be\/wp-content\/uploads\/2021\/03\/nasa-_SFJhRPzJHs-unsplash-scaled.jpg","width":2560,"height":1704,"caption":"Een UBO stopt niet bij de landsgrens"},{"@type":"BreadcrumbList","@id":"https:\/\/www.altares.be\/blog\/compliance\/een-ubo-stopt-niet-bij-de-landsgrens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.altares.be\/"},{"@type":"ListItem","position":2,"name":"Een UBO stopt niet bij de landsgrens"}]},{"@type":"WebSite","@id":"https:\/\/www.altares.be\/#website","url":"https:\/\/www.altares.be\/","name":"Altares","description":"partenaire du r\u00e9seau mondial de Dun\u00a0&amp;\u00a0Bradstreet","publisher":{"@id":"https:\/\/www.altares.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altares.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.altares.be\/#organization","name":"Altares","url":"https:\/\/www.altares.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.altares.be\/#\/schema\/logo\/image\/","url":"https:\/\/www.altares.be\/wp-content\/uploads\/2021\/03\/Altares_RGB_liggend.svg","contentUrl":"https:\/\/www.altares.be\/wp-content\/uploads\/2021\/03\/Altares_RGB_liggend.svg","width":145.57333,"height":20.52,"caption":"Altares"},"image":{"@id":"https:\/\/www.altares.be\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.altares.be\/#\/schema\/person\/51de691f2083dfb43a1308c2f4b31b25","name":"Anne de Geus","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/secure.gravatar.com\/avatar\/f637b195224280571c9d07af4b1944ab0828c5f570216b88cc1631795077e5eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f637b195224280571c9d07af4b1944ab0828c5f570216b88cc1631795077e5eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f637b195224280571c9d07af4b1944ab0828c5f570216b88cc1631795077e5eb?s=96&d=mm&r=g","caption":"Anne de Geus"}}]}},"_links":{"self":[{"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/posts\/12365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/comments?post=12365"}],"version-history":[{"count":0,"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/posts\/12365\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/media\/12366"}],"wp:attachment":[{"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/media?parent=12365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/categories?post=12365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altares.be\/fr\/wp-json\/wp\/v2\/tags?post=12365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}